{"id":3222,"date":"2022-10-06T15:58:46","date_gmt":"2022-10-06T15:58:46","guid":{"rendered":"https:\/\/madoquaventures.com\/?p=3222"},"modified":"2022-10-06T15:59:35","modified_gmt":"2022-10-06T15:59:35","slug":"consorcio-madoqua-expresso","status":"publish","type":"post","link":"https:\/\/madoqua.com\/pt-pt\/consorcio-madoqua-expresso\/","title":{"rendered":"Cons\u00f3rcio Madoqua Power 2X contrata empresa de engenharia para projeto de hidrog\u00e9nio verde em Sines"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">O cons\u00f3rcio Madoqua Power 2X contratou a NextChem, do grupo italiano Maire Tecnimont, para os estudos de engenharia do projeto de hidrog\u00e9nio verde de Sines, cujo investimento \u00e9 estimado em cerca de mil milh\u00f5es de euros<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><em><a href=\"https:\/\/expresso.pt\/economia\/2022-09-06-Consorcio-Madoqua-Power-2X-contrata-empresa-de-engenharia-para-projeto-de-hidrogenio-verde-em-Sines-69c8633a\" data-type=\"URL\" data-id=\"https:\/\/expresso.pt\/economia\/2022-09-06-Consorcio-Madoqua-Power-2X-contrata-empresa-de-engenharia-para-projeto-de-hidrogenio-verde-em-Sines-69c8633a\" target=\"_blank\" rel=\"noreferrer noopener\">6 de Setembro em Expresso<\/a><\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O cons\u00f3rcio Madoqua Power 2X, que junta a empresa portuguesa Madoqua Renewables, a holandesa Power 2X e a dinamarquesa Copenhagem Infrastructure Partners, assinou esta ter\u00e7a-feira em Mil\u00e3o um contrato de servi\u00e7os de engenharia com a empresa NextChem, do grupo italiano Maire Tecnimont, para que esta avance com os estudos de engenharia necess\u00e1rios para o licenciamento do projeto de hidrog\u00e9nio verde que o cons\u00f3rcio quer desenvolver em Sines.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O contrato foi firmado durante a feira GasTech, que decorre em Mil\u00e3o, na presen\u00e7a do secret\u00e1rio de Estado do Ambiente e da Energia, Jo\u00e3o Galamba, que afirmou, na ocasi\u00e3o, que \u201ca neutralidade clim\u00e1tica at\u00e9 2050 exige decis\u00f5es ousadas sobre investimentos sustent\u00e1veis com foco nos objetivos energ\u00e9ticos e clim\u00e1ticos, permitindo ao mesmo tempo a recupera\u00e7\u00e3o econ\u00f3mica\u201d, segundo o comunicado divulgado esta ter\u00e7a-feira pelo cons\u00f3rcio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEstamos entusiasmados por trazer a Maire Tecnimont S.p.A e a NextChem para acelerar as fases de licenciamento e engenharia do nosso projeto\u201d, referiu, por seu turno, o presidente executivo da Madoqua Renewables, Rogaciano Rebelo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O projeto que o cons\u00f3rcio tem para Sines prev\u00ea produzir anualmente 50 mil toneladas de hidrog\u00e9nio verde (a partir de uma capacidade de eletr\u00f3lise de 500 megawatts), bem como at\u00e9 500 mil toneladas de amon\u00edaco de origem renov\u00e1vel. Um dos objetivos \u00e9 exportar esta produ\u00e7\u00e3o para os mercados do noroeste da Europa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O investimento estimado em Sines nestas unidades de hidrog\u00e9nio e amon\u00edaco verde rondar\u00e1 os mil milh\u00f5es de euros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O cons\u00f3rcio Madoqua Power 2X contratou a NextChem, do grupo italiano Maire Tecnimont, para os estudos de engenharia do projeto de hidrog\u00e9nio verde de Sines, cujo investimento \u00e9 estimado em cerca de mil milh\u00f5es de euros 6 de Setembro em Expresso O cons\u00f3rcio Madoqua Power 2X, que junta a empresa portuguesa Madoqua Renewables, a holandesa [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2873,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[31],"tags":[],"class_list":["post-3222","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-press-release-pt-pt"],"_links":{"self":[{"href":"https:\/\/madoqua.com\/pt-pt\/wp-json\/wp\/v2\/posts\/3222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/madoqua.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/madoqua.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/madoqua.com\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/madoqua.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=3222"}],"version-history":[{"count":2,"href":"https:\/\/madoqua.com\/pt-pt\/wp-json\/wp\/v2\/posts\/3222\/revisions"}],"predecessor-version":[{"id":3226,"href":"https:\/\/madoqua.com\/pt-pt\/wp-json\/wp\/v2\/posts\/3222\/revisions\/3226"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/madoqua.com\/pt-pt\/wp-json\/wp\/v2\/media\/2873"}],"wp:attachment":[{"href":"https:\/\/madoqua.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=3222"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/madoqua.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=3222"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/madoqua.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=3222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}